{"id":3105,"date":"2024-10-14T11:46:28","date_gmt":"2024-10-14T09:46:28","guid":{"rendered":"https:\/\/arial-industries.com\/?post_type=job_listing&#038;p=3105"},"modified":"2024-11-07T00:36:11","modified_gmt":"2024-11-06T23:36:11","slug":"pilote-investissement-h-f","status":"expired","type":"job_listing","link":"http:\/\/arial-industries.com\/?post_type=job_listing&p=3105","title":{"rendered":"PILOTE INVESTISSEMENT (H\/F)"},"content":{"rendered":"<p><strong>QUI SOMMES-NOUS&nbsp;?<\/strong><\/p>\n<p>ARIAL Industries est une soci\u00e9t\u00e9 d\u2019ing\u00e9nierie et d\u2019assistance technique en forte croissance dans les m\u00e9tiers de la m\u00e9canique, de l\u2019\u00e9lectricit\u00e9 et des syst\u00e8mes embarqu\u00e9s. Nous intervenons sur le plan national et europ\u00e9en pour des programmes d\u2019envergure aupr\u00e8s des grands comptes des secteurs a\u00e9ronautique, automobile, spatial, \u00e9nergies et d\u00e9fense.<\/p>\n<p><strong>NOS VALEURS&nbsp;?<\/strong><\/p>\n<p>Notre politique RH est construite autour d\u2019un ma\u00eetre mot, l\u2019Humain. Nous souhaitons promouvoir le sens du service et la r\u00e9activit\u00e9, l\u2019\u00e9coute et la reconnaissance.<\/p>\n<p><strong>NOS OPPORTUNITES \/ LES MISSIONS<\/strong><\/p>\n<p>Dans le cadre de nos projets dans le secteur automobile, nous recherchons un Pilote Investissement (H\/F) afin de piloter les phases d\u2019\u00e9tude, de d\u00e9veloppement et d\u2019industrialisation du process Peinture.<\/p>\n<p>Vous serez garant(e) de l\u2019avancement technique et financier Qualit\u00e9 \/ Co\u00fbts \/ D\u00e9lais.<\/p>\n<p>Le poste est \u00e0 pourvoir depuis Sandouville.<\/p>\n<p>Les missions propos\u00e9es&nbsp;:<\/p>\n<ul>\n<li>Coordonner les diff\u00e9rentes parties prenantes au projet (Bureau d\u2019Etudes, Production Usine, M\u00e9tiers),<\/li>\n<li>Participer \u00e0 l\u2019\u00e9laboration des sp\u00e9cifications techniques produits\/process,<\/li>\n<li>Etablir des chiffrages et des appels d\u2019offres,<\/li>\n<li>Planifier les phases de fabrication et de d\u00e9ploiement,<\/li>\n<li>Assurer le suivi de chantier et la mont\u00e9e en cadence,<\/li>\n<li>Garantir la livraison de pr\u00e9s\u00e9rie en respectant le niveau de qualit\u00e9 requis.<\/li>\n<\/ul>\n<p><strong>PROFIL RECHERCH\u00c9<\/strong><\/p>\n<p>De formation Bac+5 en M\u00e9canique, G\u00e9nie Industriel ou Industrialisation, vous justifiez d\u2019une exp\u00e9rience de 5 ans minimum sur un poste similaire dans le secteur automobile.<\/p>\n<p>Vous connaissez les cha\u00eenes de cotes, l\u2019isostatisme, la qualification d\u2019outillages et les proc\u00e9dures de r\u00e9ception de moyens.<\/p>\n<p>L\u2019anglais (lu, \u00e9crit, parl\u00e9) est n\u00e9cessaire sur ce poste.<\/p>\n<p>Nous recherchons des profils autonomes, rigoureux et ayant un bon relationnel.<\/p>\n<p><strong>SALAIRE ET AVANTAGES<\/strong><\/p>\n<ul>\n<li>Entre 37K et 47K\/ brut par an en fonction du profil,<\/li>\n<li>Contrat CDI,<\/li>\n<li>Vous b\u00e9n\u00e9ficiez d\u2019une prise en charge \u00e0 hauteur de 50% de la mutuelle entreprise, 100% pour la pr\u00e9voyance,<\/li>\n<li>Prime de cooptation, primes de vacances et autres primes<\/li>\n<li>Paniers repas par mois,<\/li>\n<li>RTT,<\/li>\n<li>Participez \u00e0 nos \u00e9v\u00e8nements et rencontrez toutes nos \u00e9quipes Arial Industries,<\/li>\n<li>Plateforme Avantages (cin\u00e9ma, culture, jeux, multim\u00e9dia, ch\u00e8ques cadeaux\u2026).<\/li>\n<\/ul>\n<p><strong>VOS OPPORTUNITES CHEZ ARIAL INDUSTRIES<\/strong><\/p>\n<p>Pas de limitation ! Vous avez des objectifs professionnels ? Nous les d\u00e9finirons ensemble et serons heureux de vous aider \u00e0 les atteindre.<br \/>\nVotre s\u00e9rieux et motivation ouvriront les portes des missions qui vous int\u00e9ressent.<\/p>\n<p><strong>PROCESSUS DE RECRUTEMENT<\/strong><\/p>\n<p>&#8211; Etape 1 : Point t\u00e9l\u00e9phonique (5\/10 minutes) avec la charg\u00e9e de recrutement<br \/>\n&#8211; Etape 2 : Entretien Teams (30 minutes) avec la charg\u00e9e de recrutement<br \/>\n&#8211; Etape 3 : Entretien (1h) avec le manager technique<br \/>\n&#8211; Etape 4&nbsp;: Int\u00e9gration au sein de nos \u00e9quipes<\/p>\n<p>Nous garantissons de la r\u00e9activit\u00e9 et nous faisons en sorte de vous partager une r\u00e9ponse le plus vite possible !<\/p>\n<p>En esp\u00e9rant vous compter parmi nous tr\u00e8s prochainement.<\/p>\n","protected":false},"author":6,"featured_media":0,"template":"","meta":{"_job_location":"","_application":"arial-26136@candidatus.com","_company_name":"","_company_website":"","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0},"job_listing_region":[242],"job-categories":[60],"job-types":[],"_links":{"self":[{"href":"http:\/\/arial-industries.com\/index.php\/wp-json\/wp\/v2\/job-listings\/3105"}],"collection":[{"href":"http:\/\/arial-industries.com\/index.php\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"http:\/\/arial-industries.com\/index.php\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"http:\/\/arial-industries.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"wp:attachment":[{"href":"http:\/\/arial-industries.com\/index.php\/wp-json\/wp\/v2\/media?parent=3105"}],"wp:term":[{"taxonomy":"job_listing_region","embeddable":true,"href":"http:\/\/arial-industries.com\/index.php\/wp-json\/wp\/v2\/job_listing_region?post=3105"},{"taxonomy":"job_listing_category","embeddable":true,"href":"http:\/\/arial-industries.com\/index.php\/wp-json\/wp\/v2\/job-categories?post=3105"},{"taxonomy":"job_listing_type","embeddable":true,"href":"http:\/\/arial-industries.com\/index.php\/wp-json\/wp\/v2\/job-types?post=3105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}